{"id":761,"count":1,"description":"","link":"https:\/\/new-york-trend.com\/en\/tag\/the-gershwin-theatre","name":"The Gershwin Theatre","slug":"the-gershwin-theatre","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/new-york-trend.com\/en\/wp-json\/wp\/v2\/tags\/761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-york-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/new-york-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/new-york-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}