{"id":1293,"count":1,"description":"","link":"https:\/\/new-york-trend.com\/ru\/tag\/%d0%bf%d0%b5%d1%81%d0%bd%d0%b8-%d0%b3%d1%80%d1%83%d0%bf%d0%bf%d1%8b-the-strokes","name":"\u043f\u0435\u0441\u043d\u0438 \u0433\u0440\u0443\u043f\u043f\u044b The Strokes","slug":"%d0%bf%d0%b5%d1%81%d0%bd%d0%b8-%d0%b3%d1%80%d1%83%d0%bf%d0%bf%d1%8b-the-strokes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/new-york-trend.com\/ru\/wp-json\/wp\/v2\/tags\/1293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-york-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/new-york-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/new-york-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=1293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}