{"id":2645,"count":1,"description":"","link":"https:\/\/new-york-trend.com\/uk\/tag\/istoriya-john-street-theatre","name":"\u0456\u0441\u0442\u043e\u0440\u0456\u044f John Street Theatre","slug":"istoriya-john-street-theatre","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/new-york-trend.com\/uk\/wp-json\/wp\/v2\/tags\/2645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-york-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/new-york-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/new-york-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=2645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}